{"id":11969,"date":"2024-08-09T12:21:31","date_gmt":"2024-08-09T12:21:31","guid":{"rendered":"https:\/\/godsheart.tv\/newdesign\/?page_id=11969"},"modified":"2025-07-10T08:07:12","modified_gmt":"2025-07-10T07:07:12","slug":"ermutigung","status":"publish","type":"page","link":"https:\/\/godsheart.tv\/de\/ermutigung\/","title":{"rendered":"Ermutigung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11969\" class=\"elementor elementor-11969\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65b6186 e-flex e-con-boxed e-con e-parent\" data-id=\"65b6186\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80ffd4e elementor-widget elementor-widget-text-editor\" data-id=\"80ffd4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>&#8220;Egal, welche Fragen das Leben dir stellt, die Antworten stehen immer in Gottes Wort.&#8221;<\/em><\/p><p>In einer Welt, die oft negative Nachrichten in den Vordergrund stellt, m\u00fcssen wir regelm\u00e4\u00dfig an die Wahrheit von Gottes Wort erinnert werden, die unseren Herzen Ermutigung und Hoffnung bringt. Wir beten daf\u00fcr, dass du beim Betrachten dieser kurzen Predigtclips von Bruder Chris inspiriert wirst, die Dinge aus Gottes Perspektive zu sehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02fa6b1 e-flex e-con-boxed e-con e-parent\" data-id=\"02fa6b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5ccb30 elementor-widget elementor-widget-wpzoom-elementor-addons-portfolio-showcase\" data-id=\"a5ccb30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;portfolio_showcase_styles&quot;:&quot;default&quot;}\" data-widget_type=\"wpzoom-elementor-addons-portfolio-showcase.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"portfolio-showcase\"><div class=\"portfolio-showcase-header\"><nav class=\"portfolio-archive-taxonomies\" style=\"display:none;\">\n\t<ul class=\"portfolio-taxonomies portfolio-taxonomies-filter-by\">\n\t\t<li data-subcategory=\"151\"\t\t\tclass=\"cat-item cat-item-all current-cat\" \n\t\t\tdata-counter=\"20\"\n\t\t>\n\t\t\t<a href=\"https:\/\/godsheart.tv\/de\/portfolio\/\">All<\/a>\n\t\t<\/li>\n\t\t<li class=\"cat-item-none\">No categories<\/li>\t<\/ul>\n<\/nav><\/div><!-- \/\/ .portfolio-showcase-header -->\t\t\t<div data-subcategory=\"151\"\t\t\t\tdata-ajax-items-loading=\"\"\n\t\t\t\tdata-nonce=\"efd6aaaafd\"\n\t\t\t\tdata-count-nonce=\"cc2f15b30d\"\n\t\t\t\tdata-items-count=\"20\"\n\t\t\t\tdata-instance=\"{&quot;layout_type&quot;:&quot;full-width&quot;,&quot;col_number&quot;:&quot;3&quot;,&quot;aspect_ratio&quot;:&quot;portrait&quot;,&quot;background_video&quot;:true,&quot;show_masonry&quot;:false,&quot;show_popup&quot;:true,&quot;show_popup_caption&quot;:false,&quot;show_popup_excerpt&quot;:false,&quot;show_excerpt&quot;:false,&quot;view_all_btn&quot;:true,&quot;readmore_text&quot;:&quot;Read More&quot;,&quot;enable_director_name&quot;:false,&quot;enable_year&quot;:false,&quot;enable_category&quot;:false,&quot;show_count&quot;:600,&quot;show_categories&quot;:true,&quot;always_play_background_video&quot;:false}\"\n\t\t\t\tclass=\"portfolio-grid  portfolio_with_space col_no_3 \"\n\t\t\t>\n\t\t\t\t            <article id=\"post-17825\" class=\" portfolio_151_item portfolio_item post-17825 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/no-moment-spent-in-gods-presence-goes-missing\/\" title=\"&#8220;Nackt kam ich aus dem Scho\u00df meiner Mutter; nackt werde ich zur\u00fcckkehren.&#8221; (Hiob\u00a01:21)\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=nJzW5nbMGMQ\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/no-moment-spent-in-gods-presence-goes-missing\/\"\n                                       title=\"&#8220;Nackt kam ich aus dem Scho\u00df meiner Mutter; nackt werde ich zur\u00fcckkehren.&#8221; (Hiob\u00a01:21)\">&#8220;Nackt kam ich aus dem Scho\u00df meiner Mutter; nackt werde ich zur\u00fcckkehren.&#8221; (Hiob\u00a01:21)<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2015\/06\/maxresdefault-1-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19381\" class=\" portfolio_151_item portfolio_item post-19381 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/gott-weis-es-am-besten\/\" title=\"GOTT wei\u00df es am besten!!!\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=DmzPptvFOis\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/gott-weis-es-am-besten\/\"\n                                       title=\"GOTT wei\u00df es am besten!!!\">GOTT wei\u00df es am besten!!!<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-103-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19384\" class=\" portfolio_151_item portfolio_item post-19384 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/deine-grose-liebe-zu-gott-wird-dich-gros-machen\/\" title=\"Deine gro\u00dfe Liebe zu Gott wird dich gro\u00df machen!\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=pjgCeOihesU\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/deine-grose-liebe-zu-gott-wird-dich-gros-machen\/\"\n                                       title=\"Deine gro\u00dfe Liebe zu Gott wird dich gro\u00df machen!\">Deine gro\u00dfe Liebe zu Gott wird dich gro\u00df machen!<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-104-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19387\" class=\" portfolio_151_item portfolio_item post-19387 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/vier-wege-wie-wir-den-heiligen-geist-betruben\/\" title=\"Vier Wege, wie wir den Heiligen Geist betr\u00fcben\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=__zVH42QGDg\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/vier-wege-wie-wir-den-heiligen-geist-betruben\/\"\n                                       title=\"Vier Wege, wie wir den Heiligen Geist betr\u00fcben\">Vier Wege, wie wir den Heiligen Geist betr\u00fcben<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-105-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19390\" class=\" portfolio_151_item portfolio_item post-19390 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/alles-auf-dieser-welt-ist-dem-wandel-unterworfen\/\" title=\"Alles auf dieser Welt ist dem Wandel unterworfen\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=TOliyKcyk3k\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/alles-auf-dieser-welt-ist-dem-wandel-unterworfen\/\"\n                                       title=\"Alles auf dieser Welt ist dem Wandel unterworfen\">Alles auf dieser Welt ist dem Wandel unterworfen<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-106-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19393\" class=\" portfolio_151_item portfolio_item post-19393 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/keine-herausforderung-kann-dich-uberwaltigen\/\" title=\"Keine Herausforderung kann dich \u00fcberw\u00e4ltigen!\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=J032T48hRJM\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/keine-herausforderung-kann-dich-uberwaltigen\/\"\n                                       title=\"Keine Herausforderung kann dich \u00fcberw\u00e4ltigen!\">Keine Herausforderung kann dich \u00fcberw\u00e4ltigen!<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-107-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19399\" class=\" portfolio_151_item portfolio_item post-19399 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/wenn-gott-dich-auf-dieser-reise-begleitet-hat-wird-er-dich-auch-bis-zum-ende-begleiten\/\" title=\"&#8220;Wenn Gott dich auf dieser Reise begleitet hat, wird ER dich auch bis zum Ende begleiten!&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=pth49gA62X4\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/wenn-gott-dich-auf-dieser-reise-begleitet-hat-wird-er-dich-auch-bis-zum-ende-begleiten\/\"\n                                       title=\"&#8220;Wenn Gott dich auf dieser Reise begleitet hat, wird ER dich auch bis zum Ende begleiten!&#8221;\">&#8220;Wenn Gott dich auf dieser Reise begleitet hat, wird ER dich auch bis zum Ende begleiten!&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-109-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19396\" class=\" portfolio_151_item portfolio_item post-19396 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/als-christ-ist-dein-sturm-nicht-wie-das-der-anderen\/\" title=\"&#8220;Als Christ ist dein Sturm nicht wie das der anderen&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=7VZy7v80cfU\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/als-christ-ist-dein-sturm-nicht-wie-das-der-anderen\/\"\n                                       title=\"&#8220;Als Christ ist dein Sturm nicht wie das der anderen&#8221;\">&#8220;Als Christ ist dein Sturm nicht wie das der anderen&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-108-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19402\" class=\" portfolio_151_item portfolio_item post-19402 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/du-musst-nicht-durch-den-schmerz-der-vergangenheit-gebunden-sein\/\" title=\"&#8220;Du musst nicht durch den Schmerz der Vergangenheit gebunden sein.&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=3qAKdJuTWGM\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/du-musst-nicht-durch-den-schmerz-der-vergangenheit-gebunden-sein\/\"\n                                       title=\"&#8220;Du musst nicht durch den Schmerz der Vergangenheit gebunden sein.&#8221;\">&#8220;Du musst nicht durch den Schmerz der Vergangenheit gebunden sein.&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-110-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19405\" class=\" portfolio_151_item portfolio_item post-19405 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/was-wir-nicht-essen-sollten-wir-nicht-einmal-riechen\/\" title=\"Was wir nicht ESSEN, sollten wir nicht einmal RIECHEN.\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=gXtgeKaulqc\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/was-wir-nicht-essen-sollten-wir-nicht-einmal-riechen\/\"\n                                       title=\"Was wir nicht ESSEN, sollten wir nicht einmal RIECHEN.\">Was wir nicht ESSEN, sollten wir nicht einmal RIECHEN.<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-111-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19408\" class=\" portfolio_151_item portfolio_item post-19408 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/satan-hat-keinen-zugang-zu-deinem-leben-auser-den-turen-die-du-ihm-offnest\/\" title=\"&#8220;Satan hat keinen Zugang zu deinem Leben, au\u00dfer den T\u00fcren, die du ihm \u00f6ffnest.&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=uIJGcLHw5Rg\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/satan-hat-keinen-zugang-zu-deinem-leben-auser-den-turen-die-du-ihm-offnest\/\"\n                                       title=\"&#8220;Satan hat keinen Zugang zu deinem Leben, au\u00dfer den T\u00fcren, die du ihm \u00f6ffnest.&#8221;\">&#8220;Satan hat keinen Zugang zu deinem Leben, au\u00dfer den T\u00fcren, die du ihm \u00f6ffnest.&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-112-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19411\" class=\" portfolio_151_item portfolio_item post-19411 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/gottlicher-charakter\/\" title=\"G\u00f6ttlicher Charakter\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=CsgaoboEjCU\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/gottlicher-charakter\/\"\n                                       title=\"G\u00f6ttlicher Charakter\">G\u00f6ttlicher Charakter<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-113-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19414\" class=\" portfolio_151_item portfolio_item post-19414 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/gott-will-nicht-dass-einer-von-uns-am-ende-seiner-tage-sagt-ich-hatte-ich-sollteich-wurde\/\" title=\"Gott will nicht, dass einer von uns am Ende seiner Tage sagt: Ich h\u00e4tte\u2026 Ich sollte\u2026Ich w\u00fcrde\u2026\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=xpS5R7NZcgU\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/gott-will-nicht-dass-einer-von-uns-am-ende-seiner-tage-sagt-ich-hatte-ich-sollteich-wurde\/\"\n                                       title=\"Gott will nicht, dass einer von uns am Ende seiner Tage sagt: Ich h\u00e4tte\u2026 Ich sollte\u2026Ich w\u00fcrde\u2026\">Gott will nicht, dass einer von uns am Ende seiner Tage sagt: Ich h\u00e4tte\u2026 Ich sollte\u2026Ich w\u00fcrde\u2026<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-114-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19417\" class=\" portfolio_151_item portfolio_item post-19417 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/sei-nicht-enttauscht-weil-du-entmutigt-wurdest-oder-verbittert-weil-du-betrogen-wurdest\/\" title=\"Sei nicht entt\u00e4uscht, weil du entmutigt wurdest, oder verbittert, weil du betrogen wurdest!\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=gEmy92OQ27Y\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/sei-nicht-enttauscht-weil-du-entmutigt-wurdest-oder-verbittert-weil-du-betrogen-wurdest\/\"\n                                       title=\"Sei nicht entt\u00e4uscht, weil du entmutigt wurdest, oder verbittert, weil du betrogen wurdest!\">Sei nicht entt\u00e4uscht, weil du entmutigt wurdest, oder verbittert, weil du betrogen wurdest!<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-115-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19420\" class=\" portfolio_151_item portfolio_item post-19420 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/satan-mag-es-schaffen-dir-schmerzen-zuzufugen-aber-lass-nicht-zu-dass-er-dein-herz-verletzt\/\" title=\"&#8220;Satan mag es schaffen, dir Schmerzen zuzuf\u00fcgen &#8211; aber lass nicht zu, dass er dein Herz verletzt.&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=x7cC_VAaFh0\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/satan-mag-es-schaffen-dir-schmerzen-zuzufugen-aber-lass-nicht-zu-dass-er-dein-herz-verletzt\/\"\n                                       title=\"&#8220;Satan mag es schaffen, dir Schmerzen zuzuf\u00fcgen &#8211; aber lass nicht zu, dass er dein Herz verletzt.&#8221;\">&#8220;Satan mag es schaffen, dir Schmerzen zuzuf\u00fcgen &#8211; aber lass nicht zu, dass er dein Herz verletzt.&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-116-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19423\" class=\" portfolio_151_item portfolio_item post-19423 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/wenn-du-alles-in-gottes-hande-legst-wirst-du-bald-gottes-hande-in-allem-sehen\/\" title=\"&#8220;Wenn du ALLES in Gottes H\u00e4nde legst, wirst du bald Gottes H\u00e4nde in ALLEM sehen!&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=PQmSmpxoyok\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/wenn-du-alles-in-gottes-hande-legst-wirst-du-bald-gottes-hande-in-allem-sehen\/\"\n                                       title=\"&#8220;Wenn du ALLES in Gottes H\u00e4nde legst, wirst du bald Gottes H\u00e4nde in ALLEM sehen!&#8221;\">&#8220;Wenn du ALLES in Gottes H\u00e4nde legst, wirst du bald Gottes H\u00e4nde in ALLEM sehen!&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-117-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19426\" class=\" portfolio_151_item portfolio_item post-19426 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/viele-sind-daran-gehindert-worden-ihr-wahres-potenzial-auszuschopfen\/\" title=\"Viele sind daran gehindert worden, ihr wahres Potenzial auszusch\u00f6pfen&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=iK09ZmC_pYg\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/viele-sind-daran-gehindert-worden-ihr-wahres-potenzial-auszuschopfen\/\"\n                                       title=\"Viele sind daran gehindert worden, ihr wahres Potenzial auszusch\u00f6pfen&#8221;\">Viele sind daran gehindert worden, ihr wahres Potenzial auszusch\u00f6pfen&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-118-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19429\" class=\" portfolio_151_item portfolio_item post-19429 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/verzweiflung-ist-gefahrlich\/\" title=\"Verzweiflung ist GEF\u00c4HRLICH!\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=GBzbIAGTi-E\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/verzweiflung-ist-gefahrlich\/\"\n                                       title=\"Verzweiflung ist GEF\u00c4HRLICH!\">Verzweiflung ist GEF\u00c4HRLICH!<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-119-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19432\" class=\" portfolio_151_item portfolio_item post-19432 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/mach-dein-herz-nicht-schmutzig\/\" title=\"Mach Dein Herz nicht schmutzig\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=DGQiAETXQsI\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/mach-dein-herz-nicht-schmutzig\/\"\n                                       title=\"Mach Dein Herz nicht schmutzig\">Mach Dein Herz nicht schmutzig<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-120-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>            <article id=\"post-19435\" class=\" portfolio_151_item portfolio_item post-19435 type-portfolio_item status-publish has-post-thumbnail hentry portfolio-encouragement\">\n            \n                    <div class=\"entry-thumbnail-popover\">\n                        <div class=\"entry-thumbnail-popover-content lightbox_popup_insp popover-content--animated\" data-show-caption=\"\" data-show-excerpt=\"\">\n\n                            <a class=\"wpz-portfolio-link\" href=\"https:\/\/godsheart.tv\/de\/video\/wenn-du-heute-eine-enttauschung-erlebst-gib-nicht-auf\/\" title=\"&#8220;Wenn du heute eine Entt\u00e4uschung erlebst, gib nicht auf&#8221;\"><\/a>\n\n                            <div class=\"entry-meta\">\n\n                                <!-- start lightbox --><a\n                                    class=\"mfp-iframe portfolio-popup-video\"\n                                    href=\"https:\/\/youtube.com\/watch?v=OlQRjUPebbw\" aria-label=\"Watch Video\"><\/a>\n                                \n                                <h3 class=\"portfolio_item-title\">\n                                    <a href=\"https:\/\/godsheart.tv\/de\/video\/wenn-du-heute-eine-enttauschung-erlebst-gib-nicht-auf\/\"\n                                       title=\"&#8220;Wenn du heute eine Entt\u00e4uschung erlebst, gib nicht auf&#8221;\">&#8220;Wenn du heute eine Entt\u00e4uschung erlebst, gib nicht auf&#8221;<\/a>\n                                <\/h3>\n\n                                <ul>\n                                    \n                                    \n                                                                    <\/ul>\n\n                                \n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n\n                    \n                        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"720\" src=\"https:\/\/godsheart.tv\/de\/wp-content\/uploads\/2025\/07\/maxresdefault-121-600x720.jpg\" class=\"attachment-portfolio_item-thumbnail_portrait size-portfolio_item-thumbnail_portrait wp-post-image\" alt=\"\" \/>\n                    \n\n                            <\/article>\n\t\t\t<\/div><!-- \/\/ .portfolio-grid -->\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"portfolio-preloader\">\n\t\t\t\t<div id=\"loading-39x\">\n\t\t\t\t\t<div class=\"spinner\">\n\t\t\t\t\t\t<div class=\"rect1\"><\/div> \n\t\t\t\t\t\t<div class=\"rect2\"><\/div> \n\t\t\t\t\t\t<div class=\"rect3\"><\/div> \n\t\t\t\t\t\t<div class=\"rect4\"><\/div> \n\t\t\t\t\t\t<div class=\"rect5\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n        \n\t\t<\/div><!-- \/\/ .portfolio-showcase -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&#8220;Egal, welche Fragen das Leben dir stellt, die Antworten stehen immer in Gottes Wort.&#8221; In einer Welt, die oft negative Nachrichten in den Vordergrund stellt, m\u00fcssen wir regelm\u00e4\u00dfig an die Wahrheit von Gottes Wort erinnert werden, die unseren Herzen Ermutigung und Hoffnung bringt. Wir beten daf\u00fcr, dass du beim Betrachten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-11969","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/pages\/11969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/comments?post=11969"}],"version-history":[{"count":4,"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/pages\/11969\/revisions"}],"predecessor-version":[{"id":18780,"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/pages\/11969\/revisions\/18780"}],"wp:attachment":[{"href":"https:\/\/godsheart.tv\/de\/wp-json\/wp\/v2\/media?parent=11969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}