{"id":19442,"date":"2025-05-29T12:36:00","date_gmt":"2025-05-29T11:36:00","guid":{"rendered":"https:\/\/godshearttv.com\/es\/?post_type=portfolio_item&#038;p=19442"},"modified":"2026-05-09T21:25:49","modified_gmt":"2026-05-09T20:25:49","slug":"oracion-en-el-reino-unido-milagro-en-noruega-2","status":"publish","type":"portfolio_item","link":"https:\/\/godsheart.tv\/es\/video\/oracion-en-el-reino-unido-milagro-en-noruega-2\/","title":{"rendered":"Oraci\u00f3n en el Reino Unido; \u00a1Milagro en NORUEGA!"},"content":{"rendered":"\n<figure class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Oraci\u00f3n en el Reino Unido; \u00a1Milagro en NORUEGA!\" width=\"930\" height=\"523\" src=\"https:\/\/www.youtube.com\/embed\/Xy2JTgU73hE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":19444,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":""},"portfolio":[45],"class_list":["post-19442","portfolio_item","type-portfolio_item","status-publish","has-post-thumbnail","hentry","portfolio-testimonies"],"_links":{"self":[{"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/portfolio_item\/19442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/portfolio_item"}],"about":[{"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/types\/portfolio_item"}],"author":[{"embeddable":true,"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/comments?post=19442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/media\/19444"}],"wp:attachment":[{"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/media?parent=19442"}],"wp:term":[{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/godsheart.tv\/es\/wp-json\/wp\/v2\/portfolio?post=19442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}